{"id":5264,"date":"2025-03-21T16:04:43","date_gmt":"2025-03-21T15:04:43","guid":{"rendered":"https:\/\/echasseurs.org\/giostra-femminile\/"},"modified":"2025-03-21T16:04:44","modified_gmt":"2025-03-21T15:04:44","slug":"giostra-femminile","status":"publish","type":"page","link":"https:\/\/echasseurs.org\/it\/giostra-femminile\/","title":{"rendered":"Giostra femminile"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5264\" class=\"elementor elementor-5264 elementor-141\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-5ae38eec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"47148\" data-id=\"5ae38eec\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fc87d52\" data-eae-slider=\"83386\" data-id=\"1fc87d52\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29bf0c3e elementor-widget elementor-widget-spacer\" data-id=\"29bf0c3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f8ad8e7 elementor-widget elementor-widget-heading\" data-id=\"3f8ad8e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">GIOSTRA FEMMINILE<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-49c09763 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"30883\" data-id=\"49c09763\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57e3670c\" data-eae-slider=\"50325\" data-id=\"57e3670c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b0aa58d elementor-widget__width-inherit elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"2b0aa58d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c66d1e5 elementor-nav-menu__align-end elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"7c66d1e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-background e--animation-fade\">\n\t\t\t\t<ul id=\"menu-1-7c66d1e5\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1635\"><a href=\"https:\/\/echasseurs.org\/it\/\" class=\"elementor-item\">Homepage<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1637\"><a href=\"https:\/\/echasseurs.org\/it\/giostra-dei-trampolieri-di-namur\/\" class=\"elementor-item\">Scoprire<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1639\"><a href=\"https:\/\/echasseurs.org\/it\/contattaci\/\" class=\"elementor-item\">Contattaci!<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1640\"><a href=\"https:\/\/echasseurs.org\/it\/i-trampoli-da-combattimento-di-namur\/\" class=\"elementor-item\">I nostri trampoli<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1641\"><a href=\"https:\/\/echasseurs.org\/it\/il-trampolo-doro-un-momento-clou-del-folclore-di-namur-e-dei-festival-di-vallonia\/\" class=\"elementor-item\">Il trampolo d\u2019oro<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5297\"><a href=\"https:\/\/echasseurs.org\/it\/giostra-femminile\/\" class=\"elementor-item\">Giostra femminile<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5296\"><a href=\"https:\/\/echasseurs.org\/it\/le-giostre-su-trampoli-di-namur-patrimonio-culturale-immateriale-dellumanita\/\" class=\"elementor-item\">Patrimonio dell\u2019umanit\u00e0<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4094\"><a href=\"https:\/\/echasseurs.org\/it\/stampa\/\" class=\"elementor-item\">Stampa<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-it wpml-ls-current-language wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-3-it\"><a href=\"https:\/\/echasseurs.org\/it\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-3-it\" class=\"elementor-item\"><span class=\"wpml-ls-native\" lang=\"it\">Italiano<\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-fr wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-fr\"><a href=\"https:\/\/echasseurs.org\/\" title=\"Passa a Fran\u00e7ais\" aria-label=\"Passa a Fran\u00e7ais\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"fr\">Fran\u00e7ais<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-en\"><a href=\"https:\/\/echasseurs.org\/en\/\" title=\"Passa a English\" aria-label=\"Passa a English\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"en\">English<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-nl wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-nl\"><a href=\"https:\/\/echasseurs.org\/nl\/\" title=\"Passa a Nederlands\" aria-label=\"Passa a Nederlands\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"nl\">Nederlands<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-de wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-de\"><a href=\"https:\/\/echasseurs.org\/de\/\" title=\"Passa a Deutsch\" aria-label=\"Passa a Deutsch\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"de\">Deutsch<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-es\"><a href=\"https:\/\/echasseurs.org\/es\/\" title=\"Passa a Espa\u00f1ol\" aria-label=\"Passa a Espa\u00f1ol\" class=\"elementor-sub-item\"><span class=\"wpml-ls-native\" lang=\"es\">Espa\u00f1ol<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu di commutazione\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-7c66d1e5\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1635\"><a href=\"https:\/\/echasseurs.org\/it\/\" class=\"elementor-item\" tabindex=\"-1\">Homepage<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1637\"><a href=\"https:\/\/echasseurs.org\/it\/giostra-dei-trampolieri-di-namur\/\" class=\"elementor-item\" tabindex=\"-1\">Scoprire<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1639\"><a href=\"https:\/\/echasseurs.org\/it\/contattaci\/\" class=\"elementor-item\" tabindex=\"-1\">Contattaci!<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1640\"><a href=\"https:\/\/echasseurs.org\/it\/i-trampoli-da-combattimento-di-namur\/\" class=\"elementor-item\" tabindex=\"-1\">I nostri trampoli<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1641\"><a href=\"https:\/\/echasseurs.org\/it\/il-trampolo-doro-un-momento-clou-del-folclore-di-namur-e-dei-festival-di-vallonia\/\" class=\"elementor-item\" tabindex=\"-1\">Il trampolo d\u2019oro<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5297\"><a href=\"https:\/\/echasseurs.org\/it\/giostra-femminile\/\" class=\"elementor-item\" tabindex=\"-1\">Giostra femminile<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5296\"><a href=\"https:\/\/echasseurs.org\/it\/le-giostre-su-trampoli-di-namur-patrimonio-culturale-immateriale-dellumanita\/\" class=\"elementor-item\" tabindex=\"-1\">Patrimonio dell\u2019umanit\u00e0<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-4094\"><a href=\"https:\/\/echasseurs.org\/it\/stampa\/\" class=\"elementor-item\" tabindex=\"-1\">Stampa<\/a><\/li>\n<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-it wpml-ls-current-language wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-has-children menu-item-wpml-ls-3-it\"><a href=\"https:\/\/echasseurs.org\/it\/\" aria-current=\"page\" aria-expanded=\"false\" aria-controls=\"wpml-ls-submenu-wpml-ls-3-it\" class=\"elementor-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"it\">Italiano<\/span><\/a>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-fr wpml-ls-menu-item wpml-ls-first-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-fr\"><a href=\"https:\/\/echasseurs.org\/\" title=\"Passa a Fran\u00e7ais\" aria-label=\"Passa a Fran\u00e7ais\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"fr\">Fran\u00e7ais<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-en wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-en\"><a href=\"https:\/\/echasseurs.org\/en\/\" title=\"Passa a English\" aria-label=\"Passa a English\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"en\">English<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-nl wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-nl\"><a href=\"https:\/\/echasseurs.org\/nl\/\" title=\"Passa a Nederlands\" aria-label=\"Passa a Nederlands\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"nl\">Nederlands<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-de wpml-ls-menu-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-de\"><a href=\"https:\/\/echasseurs.org\/de\/\" title=\"Passa a Deutsch\" aria-label=\"Passa a Deutsch\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"de\">Deutsch<\/span><\/a><\/li>\n\t<li class=\"menu-item wpml-ls-slot-3 wpml-ls-item wpml-ls-item-es wpml-ls-menu-item wpml-ls-last-item menu-item-type-wpml_ls_menu_item menu-item-object-wpml_ls_menu_item menu-item-wpml-ls-3-es\"><a href=\"https:\/\/echasseurs.org\/es\/\" title=\"Passa a Espa\u00f1ol\" aria-label=\"Passa a Espa\u00f1ol\" class=\"elementor-sub-item\" tabindex=\"-1\"><span class=\"wpml-ls-native\" lang=\"es\">Espa\u00f1ol<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-137ec31d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"10588\" data-id=\"137ec31d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-488cf136\" data-eae-slider=\"52\" data-id=\"488cf136\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23c18a97 elementor-widget elementor-widget-heading\" data-id=\"23c18a97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">STORICO!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11343914 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"11343914\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-e094a1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"72098\" data-id=\"e094a1f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba89b78\" data-eae-slider=\"75971\" data-id=\"ba89b78\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5bf282a elementor-widget elementor-widget-image\" data-id=\"5bf282a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/echasseurs.org\/wp-content\/uploads\/2022\/09\/Joutes-Echasseuses-Namur-2022-Skuds-O-683x1024.jpg\" class=\"attachment-large size-large wp-image-4566\" alt=\"\" srcset=\"https:\/\/echasseurs.org\/wp-content\/uploads\/2022\/09\/Joutes-Echasseuses-Namur-2022-Skuds-O-683x1024.jpg 683w, https:\/\/echasseurs.org\/wp-content\/uploads\/2022\/09\/Joutes-Echasseuses-Namur-2022-Skuds-O-200x300.jpg 200w, https:\/\/echasseurs.org\/wp-content\/uploads\/2022\/09\/Joutes-Echasseuses-Namur-2022-Skuds-O-768x1152.jpg 768w, https:\/\/echasseurs.org\/wp-content\/uploads\/2022\/09\/Joutes-Echasseuses-Namur-2022-Skuds-O-1024x1536.jpg 1024w, https:\/\/echasseurs.org\/wp-content\/uploads\/2022\/09\/Joutes-Echasseuses-Namur-2022-Skuds-O.jpg 1365w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8843212\" data-eae-slider=\"14121\" data-id=\"8843212\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44358cd elementor-widget elementor-widget-text-editor\" data-id=\"44358cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDopo pi\u00f9 di 600 anni di giostre esclusivamente maschili, le Echasseuses hanno ufficialmente fatto la storia il 17 settembre 2022. La loro prima giostra si \u00e8 svolta nel cuore delle Feste della Vallonia, in Piazza del Teatro.\r\n\r\nAccolte immediatamente dai cittadini di Namur, le Echasseuses fanno ora parte del ricco patrimonio immateriale della citt\u00e0.\r\n\r\nIn occasione della loro prima giostra, \u00e8 stato creato un nuovo trofeo: il Trampolo di Diamante. Da ora in poi, questo trofeo viene messo in palio ogni anno durante le Feste della Vallonia, proprio come il Trampolo d&#8217;Oro per gli uomini.\r\n\r\n<strong>Vincitrici del Trampolo di Diamante:<\/strong>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd44e69 elementor-widget elementor-widget-shortcode\" data-id=\"bd44e69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<table id=\"tablepress-2\" class=\"tablepress tablepress-id-2\">\n<thead>\n<tr class=\"row-1\">\n\t<th class=\"column-1\">Ann\u00e9e<\/th><th class=\"column-2\">Echasse de diamant<\/th><th class=\"column-3\">Compagnie<\/th>\n<\/tr>\n<\/thead>\n<tbody class=\"row-striping row-hover\">\n<tr class=\"row-2\">\n\t<td class=\"column-1\">2022<\/td><td class=\"column-2\">Manon WELSCHEN<\/td><td class=\"column-3\">Avresses<\/td>\n<\/tr>\n<tr class=\"row-3\">\n\t<td class=\"column-1\">2023<\/td><td class=\"column-2\">Lucie GROGNARD<\/td><td class=\"column-3\">M\u00e9lans<\/td>\n<\/tr>\n<tr class=\"row-4\">\n\t<td class=\"column-1\">2024<\/td><td class=\"column-2\">C\u00e9lestine  BEAUJOT<\/td><td class=\"column-3\">M\u00e9lans<\/td>\n<\/tr>\n<tr class=\"row-5\">\n\t<td class=\"column-1\">2025<\/td><td class=\"column-2\">Manon WELSCHEN<\/td><td class=\"column-3\">Avresses<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<!-- #tablepress-2 from cache --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-fe973e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"67270\" data-id=\"fe973e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cece588\" data-eae-slider=\"49496\" data-id=\"cece588\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd80999 elementor-widget elementor-widget-heading\" data-id=\"fd80999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0569f26 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0569f26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-2872944 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"1620\" data-id=\"2872944\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29efae0\" data-eae-slider=\"67999\" data-id=\"29efae0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bffff7d elementor-widget elementor-widget-text-editor\" data-id=\"bffff7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d674360\" data-eae-slider=\"62349\" data-id=\"d674360\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:4606,&quot;url&quot;:&quot;https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Namur-Stilt-jousting-first-women-joust-Skuds-O.jpg&quot;},{&quot;id&quot;:4580,&quot;url&quot;:&quot;https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Echasseuses-Premiere-Joute-Feminine-Margaux-O.jpg&quot;},{&quot;id&quot;:4334,&quot;url&quot;:&quot;https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/20220917_0077_Web.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d2b5ac elementor-widget elementor-widget-spacer\" data-id=\"7d2b5ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-a03462a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"72454\" data-id=\"a03462a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ae5b4b\" data-eae-slider=\"48398\" data-id=\"8ae5b4b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be635a0 elementor-widget elementor-widget-video\" data-id=\"be635a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot; &quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>GIOSTRA FEMMINILE STORICO! Dopo pi\u00f9 di 600 anni di giostre esclusivamente maschili, le Echasseuses hanno ufficialmente fatto la storia il 17 settembre 2022. La loro prima giostra si \u00e8 svolta nel cuore delle Feste della Vallonia, in Piazza del Teatro. Accolte immediatamente dai cittadini di Namur, le Echasseuses fanno ora parte del ricco patrimonio immateriale [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1928,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5264","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giostra femminile - Les Echasseurs Namurois<\/title>\n<meta name=\"description\" content=\"Un patrimonio immateriale aperto alle donne: le &quot;Echasseuses&quot;, giostratrici sui trampoli a Namur (Belgio).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/echasseurs.org\/it\/giostra-femminile\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giostra femminile - Les Echasseurs Namurois\" \/>\n<meta property=\"og:description\" content=\"Un patrimonio immateriale aperto alle donne: le &quot;Echasseuses&quot;, giostratrici sui trampoli a Namur (Belgio).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/echasseurs.org\/it\/giostra-femminile\/\" \/>\n<meta property=\"og:site_name\" content=\"Les Echasseurs Namurois\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/echasseurs\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T15:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/Echasseurs-Jouteuses-Echasses.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1919\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EchasseursNamur\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/\",\"url\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/\",\"name\":\"Giostra femminile - Les Echasseurs Namurois\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Echasseurs-Jouteuses-Echasses.jpg\",\"datePublished\":\"2025-03-21T15:04:43+00:00\",\"dateModified\":\"2025-03-21T15:04:44+00:00\",\"description\":\"Un patrimonio immateriale aperto alle donne: le \\\"Echasseuses\\\", giostratrici sui trampoli a Namur (Belgio).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Echasseurs-Jouteuses-Echasses.jpg\",\"contentUrl\":\"https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Echasseurs-Jouteuses-Echasses.jpg\",\"width\":1919,\"height\":933,\"caption\":\"Un peu partout dans Namur, des femmes et jeunes filles s'entra\u00eenent \u00e0 la joute sur \u00e9chasses, (c)Aurore Lumaye\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/giostra-femminile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giostra femminile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/\",\"name\":\"Les Echasseurs Namurois\",\"description\":\"Joute sur \u00e9chasses de Namur depuis 1411.\",\"publisher\":{\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/#organization\",\"name\":\"Les Echasseurs Namurois\",\"url\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon-1.png\",\"contentUrl\":\"https:\\\/\\\/echasseurs.org\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/favicon-1.png\",\"width\":160,\"height\":160,\"caption\":\"Les Echasseurs Namurois\"},\"image\":{\"@id\":\"https:\\\/\\\/echasseurs.org\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/echasseurs\",\"https:\\\/\\\/x.com\\\/EchasseursNamur\",\"https:\\\/\\\/www.instagram.com\\\/echasseurs\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/echasseurs\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/EchasseursNamurois\\\/\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00e9chasseurs_namurois\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giostra femminile - Les Echasseurs Namurois","description":"Un patrimonio immateriale aperto alle donne: le \"Echasseuses\", giostratrici sui trampoli a Namur (Belgio).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/echasseurs.org\/it\/giostra-femminile\/","og_locale":"it_IT","og_type":"article","og_title":"Giostra femminile - Les Echasseurs Namurois","og_description":"Un patrimonio immateriale aperto alle donne: le \"Echasseuses\", giostratrici sui trampoli a Namur (Belgio).","og_url":"https:\/\/echasseurs.org\/it\/giostra-femminile\/","og_site_name":"Les Echasseurs Namurois","article_publisher":"https:\/\/www.facebook.com\/echasseurs","article_modified_time":"2025-03-21T15:04:44+00:00","og_image":[{"width":1919,"height":933,"url":"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/Echasseurs-Jouteuses-Echasses.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EchasseursNamur","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/echasseurs.org\/it\/giostra-femminile\/","url":"https:\/\/echasseurs.org\/it\/giostra-femminile\/","name":"Giostra femminile - Les Echasseurs Namurois","isPartOf":{"@id":"https:\/\/echasseurs.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/echasseurs.org\/it\/giostra-femminile\/#primaryimage"},"image":{"@id":"https:\/\/echasseurs.org\/it\/giostra-femminile\/#primaryimage"},"thumbnailUrl":"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/Echasseurs-Jouteuses-Echasses.jpg","datePublished":"2025-03-21T15:04:43+00:00","dateModified":"2025-03-21T15:04:44+00:00","description":"Un patrimonio immateriale aperto alle donne: le \"Echasseuses\", giostratrici sui trampoli a Namur (Belgio).","breadcrumb":{"@id":"https:\/\/echasseurs.org\/it\/giostra-femminile\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/echasseurs.org\/it\/giostra-femminile\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/echasseurs.org\/it\/giostra-femminile\/#primaryimage","url":"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/Echasseurs-Jouteuses-Echasses.jpg","contentUrl":"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/Echasseurs-Jouteuses-Echasses.jpg","width":1919,"height":933,"caption":"Un peu partout dans Namur, des femmes et jeunes filles s'entra\u00eenent \u00e0 la joute sur \u00e9chasses, (c)Aurore Lumaye"},{"@type":"BreadcrumbList","@id":"https:\/\/echasseurs.org\/it\/giostra-femminile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/echasseurs.org\/it\/"},{"@type":"ListItem","position":2,"name":"Giostra femminile"}]},{"@type":"WebSite","@id":"https:\/\/echasseurs.org\/it\/#website","url":"https:\/\/echasseurs.org\/it\/","name":"Les Echasseurs Namurois","description":"Joute sur \u00e9chasses de Namur depuis 1411.","publisher":{"@id":"https:\/\/echasseurs.org\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/echasseurs.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/echasseurs.org\/it\/#organization","name":"Les Echasseurs Namurois","url":"https:\/\/echasseurs.org\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/echasseurs.org\/it\/#\/schema\/logo\/image\/","url":"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/favicon-1.png","contentUrl":"https:\/\/echasseurs.org\/wp-content\/uploads\/2020\/08\/favicon-1.png","width":160,"height":160,"caption":"Les Echasseurs Namurois"},"image":{"@id":"https:\/\/echasseurs.org\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/echasseurs","https:\/\/x.com\/EchasseursNamur","https:\/\/www.instagram.com\/echasseurs\/","https:\/\/www.pinterest.fr\/echasseurs","https:\/\/www.youtube.com\/c\/EchasseursNamurois\/","https:\/\/fr.wikipedia.org\/wiki\/\u00e9chasseurs_namurois"]}]}},"_links":{"self":[{"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/pages\/5264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/comments?post=5264"}],"version-history":[{"count":1,"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/pages\/5264\/revisions"}],"predecessor-version":[{"id":5265,"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/pages\/5264\/revisions\/5265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/media\/1928"}],"wp:attachment":[{"href":"https:\/\/echasseurs.org\/it\/wp-json\/wp\/v2\/media?parent=5264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}